{"id":1844,"date":"2022-11-20T09:40:49","date_gmt":"2022-11-20T08:40:49","guid":{"rendered":"https:\/\/mis.saturn.lws-servers.be\/?post_type=collab&#038;p=1844"},"modified":"2023-10-26T10:49:18","modified_gmt":"2023-10-26T08:49:18","slug":"evs-off-grid-with-optima","status":"publish","type":"collab","link":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/","title":{"rendered":"EVs off-grid with OPTIMA"},"content":{"rendered":"<p>Monroe\u00ae Intelligent Suspension potenzia l&#8217;autonomia dei veicoli elettrici con OPTIMA\u00ae Batteries e Rivian\u00ae.<\/p>\n","protected":false},"featured_media":947,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-1844","collab","type-collab","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EVs off-grid with OPTIMA - Monroe Ride Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EVs off-grid with OPTIMA - Monroe Ride Solutions\" \/>\n<meta property=\"og:description\" content=\"Monroe\u00ae Intelligent Suspension potenzia l&#8217;autonomia dei veicoli elettrici con OPTIMA\u00ae Batteries e Rivian\u00ae.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/\" \/>\n<meta property=\"og:site_name\" content=\"Monroe Ride Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T08:49:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monroeridesolutions.com\/wp-content\/uploads\/2023\/07\/mis-partners-collab-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/\",\"url\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/\",\"name\":\"EVs off-grid with OPTIMA - Monroe Ride Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mis-partners-collab-3.png\",\"datePublished\":\"2022-11-20T08:40:49+00:00\",\"dateModified\":\"2023-10-26T08:49:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mis-partners-collab-3.png\",\"contentUrl\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mis-partners-collab-3.png\",\"width\":632,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/collaborations\\\/evs-off-grid-with-optima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EVs off-grid with OPTIMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/\",\"name\":\"Monroe Ride Solutions\",\"description\":\"Ready For The Road Ahead\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monroeridesolutions.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EVs off-grid with OPTIMA - Monroe Ride Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/","og_locale":"it_IT","og_type":"article","og_title":"EVs off-grid with OPTIMA - Monroe Ride Solutions","og_description":"Monroe\u00ae Intelligent Suspension potenzia l&#8217;autonomia dei veicoli elettrici con OPTIMA\u00ae Batteries e Rivian\u00ae.","og_url":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/","og_site_name":"Monroe Ride Solutions","article_modified_time":"2023-10-26T08:49:18+00:00","og_image":[{"width":632,"height":450,"url":"https:\/\/www.monroeridesolutions.com\/wp-content\/uploads\/2023\/07\/mis-partners-collab-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/","url":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/","name":"EVs off-grid with OPTIMA - Monroe Ride Solutions","isPartOf":{"@id":"https:\/\/www.monroeridesolutions.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/#primaryimage"},"image":{"@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monroeridesolutions.com\/wp-content\/uploads\/2023\/07\/mis-partners-collab-3.png","datePublished":"2022-11-20T08:40:49+00:00","dateModified":"2023-10-26T08:49:18+00:00","breadcrumb":{"@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/#primaryimage","url":"https:\/\/www.monroeridesolutions.com\/wp-content\/uploads\/2023\/07\/mis-partners-collab-3.png","contentUrl":"https:\/\/www.monroeridesolutions.com\/wp-content\/uploads\/2023\/07\/mis-partners-collab-3.png","width":632,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.monroeridesolutions.com\/it\/collaborations\/evs-off-grid-with-optima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.monroeridesolutions.com\/it\/"},{"@type":"ListItem","position":2,"name":"EVs off-grid with OPTIMA"}]},{"@type":"WebSite","@id":"https:\/\/www.monroeridesolutions.com\/it\/#website","url":"https:\/\/www.monroeridesolutions.com\/it\/","name":"Monroe Ride Solutions","description":"Ready For The Road Ahead","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monroeridesolutions.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.monroeridesolutions.com\/it\/wp-json\/wp\/v2\/collab\/1844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monroeridesolutions.com\/it\/wp-json\/wp\/v2\/collab"}],"about":[{"href":"https:\/\/www.monroeridesolutions.com\/it\/wp-json\/wp\/v2\/types\/collab"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monroeridesolutions.com\/it\/wp-json\/wp\/v2\/media\/947"}],"wp:attachment":[{"href":"https:\/\/www.monroeridesolutions.com\/it\/wp-json\/wp\/v2\/media?parent=1844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}